{"id":2904,"date":"2023-03-29T23:34:59","date_gmt":"2023-03-29T21:34:59","guid":{"rendered":"https:\/\/15francoallemandeoccitanie.fr\/?post_type=tribe_events&#038;p=2904"},"modified":"2023-03-29T23:34:59","modified_gmt":"2023-03-29T21:34:59","slug":"un-temps-filaire-a-threaded-time","status":"publish","type":"tribe_events","link":"https:\/\/15francoallemandeoccitanie.fr\/de\/evenement\/un-temps-filaire-a-threaded-time\/","title":{"rendered":"UN TEMPS FILAIRE a threaded time"},"content":{"rendered":"<p>Galerie Lligat [hors les murs] pr\u00e9sente, sur une invitation de Layla Moget,<br \/>\nUN TEMPS FILAIRE a threaded time<br \/>\nNadia Lichtig et Muriel Valat-B<br \/>\nS\u00e9lection d&#8217;\u0153uvres sur toile et textile<br \/>\n_<br \/>\nOn parle fr\u00e9quemment dans nos soci\u00e9t\u00e9s connect\u00e9es de la technologie filaire pour d\u00e9signer des protocoles d\u2019impl\u00e9mentation de syst\u00e8mes de communication num\u00e9rique. Ainsi le c\u00e2ble de cuivre ou la fibre optique se disputent la vitesse de connexion et de transmission des donn\u00e9es. Hartmut Rosa note qu\u2019\u00e0 \u00ab l\u2019\u00e8re de la mondialisation et du r\u00e8gne de l\u2019actualit\u00e9 que repr\u00e9sente internet, le temps est de plus en plus con\u00e7u comme un \u00e9l\u00e9ment de compression ou m\u00eame d\u2019annihilation de l\u2019espace\u00bb. Mais si la technologie filaire contracte le temps et l\u2019espace, et produit ainsi une acc\u00e9l\u00e9ration sociale, nous voulons penser un autre temps filaire, un temps qui \u00e9tire, tisse et tresse nos existences et nos r\u00e9cits intimes.<\/p>\n<p>Filer en fran\u00e7ais c\u2019est travailler le fil et la trame mais c\u2019est aussi fuir, partir soudainement, je file quand je d\u00e9cide de dispara\u00eetre, quand je d\u00e9cide de faire avec la disparition. Rien de commun avec la compression mais a contrario, ce sont de longs processus plastiques de red\u00e9finition des espaces intimes et \u00e9motionnels qui sont convoqu\u00e9s et intriqu\u00e9s ici jusqu\u2019\u00e0 dissoudre les mat\u00e9riaux dans d&#8217;autres formes d\u2019existences. Ce temps filaire qui spatialise, \u00e9tire ou met le temps \u00e0 l\u2019arr\u00eat, est mis en demeure dans les \u0153uvres de Nadia Lichtig et de Muriel Valat-B. Les s\u00e9ries Pictures of Nothing ou Pelha sont avant tout des gestes qui se tiennent dans le temps long et l\u2019\u00e9tendue, entre h\u00e9ritage et t\u00e9moignage, chacune accordant \u00e0 la reprise une puissance de r\u00e9invention, d\u2019oscillation entre \u00e9panouissement et \u00e9vanouissement.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Galerie Lligat [hors les murs] pr\u00e9sente, sur une invitation de Layla Moget, UN TEMPS FILAIRE a threaded time Nadia Lichtig et Muriel Valat-B S\u00e9lection d&#8217;\u0153uvres sur toile et textile _ [&#8230;]\n","protected":false},"author":171,"featured_media":2915,"template":"","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":""},"tags":[],"tribe_events_cat":[17],"class_list":["post-2904","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-presentiel-culture","cat_presentiel-culture"],"ticketed":false,"_links":{"self":[{"href":"https:\/\/15francoallemandeoccitanie.fr\/de\/wp-json\/wp\/v2\/tribe_events\/2904","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/15francoallemandeoccitanie.fr\/de\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/15francoallemandeoccitanie.fr\/de\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/15francoallemandeoccitanie.fr\/de\/wp-json\/wp\/v2\/users\/171"}],"version-history":[{"count":2,"href":"https:\/\/15francoallemandeoccitanie.fr\/de\/wp-json\/wp\/v2\/tribe_events\/2904\/revisions"}],"predecessor-version":[{"id":2993,"href":"https:\/\/15francoallemandeoccitanie.fr\/de\/wp-json\/wp\/v2\/tribe_events\/2904\/revisions\/2993"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/15francoallemandeoccitanie.fr\/de\/wp-json\/wp\/v2\/media\/2915"}],"wp:attachment":[{"href":"https:\/\/15francoallemandeoccitanie.fr\/de\/wp-json\/wp\/v2\/media?parent=2904"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/15francoallemandeoccitanie.fr\/de\/wp-json\/wp\/v2\/tags?post=2904"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/15francoallemandeoccitanie.fr\/de\/wp-json\/wp\/v2\/tribe_events_cat?post=2904"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}