{"id":5352,"date":"2024-03-16T16:29:54","date_gmt":"2024-03-16T15:29:54","guid":{"rendered":"https:\/\/15francoallemandeoccitanie.fr\/?post_type=tribe_events&#038;p=5352"},"modified":"2024-03-16T16:29:54","modified_gmt":"2024-03-16T15:29:54","slug":"conference-de-presse-de-ledition-2024-des-festivals-jazz-en-pic-saint-loup-jazz-a-vauvert-et-jazz-a-junas","status":"publish","type":"tribe_events","link":"https:\/\/15francoallemandeoccitanie.fr\/de\/evenement\/conference-de-presse-de-ledition-2024-des-festivals-jazz-en-pic-saint-loup-jazz-a-vauvert-et-jazz-a-junas\/","title":{"rendered":"Conf\u00e9rence de presse de l\u2019\u00e9dition 2024 des festivals Jazz en Pic Saint Loup, Jazz \u00e0 Vauvert et Jazz \u00e0 Junas."},"content":{"rendered":"<p>L&#8217;\u00e9dition 2024 de Jazz \u00e0 Junas est une rencontre avec l&#8217;Allemagne !<\/p>\n<p>Organis\u00e9 depuis 1993, le Festival Jazz \u00e0 Junas est une aventure artistique, culturelle et humaine forte. Un jazz sans fronti\u00e8re, c\u2019est ce que propose Junas chaque \u00e9t\u00e9 avec des musiciens r\u00e9gionaux, nationaux et internationaux reconnus ou \u00e0 d\u00e9couvrir. Le festival tient \u00e9galement \u00e0 valoriser son territoire en investissant les lieux souvent singuliers qu\u2019offre le village de Junas : les Carri\u00e8res bien s\u00fbr, mais aussi, les rues et les places, le temple, la garrigue\u2026 afin de faire vivre le village au rythme du Jazz durant 4 jours de festival !<\/p>\n<p>Vous trouverez l\u2019invitation dans ce lien : http:\/\/maison-de-heidelberg.org\/wp-content\/uploads\/2024\/02\/Invitation-Conf%C3%A9rence-de-presse-Festival-Jazz-%C3%A0-Junas-Montpellier.pdf<br \/>\nNous restons \u00e0 votre disposition pour toutes demandes d\u2019interviews, photos, compl\u00e9ments d\u2019informations.<br \/>\nIris Conte &amp; toute l\u2019\u00e9quipe de Jazz \u00e0 Junas<\/p>\n<p>Contact Presse PQR &amp; partenariat :<br \/>\nIris Conte \u2013 H\u00e9risson productions \u2013 06 48 48 09 20<br \/>\npresse@herisson-prod.com<br \/>\n\u00c9quipe du festival : 04 66 93 01 59<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;\u00e9dition 2024 de Jazz \u00e0 Junas est une rencontre avec l&#8217;Allemagne ! Organis\u00e9 depuis 1993, le Festival Jazz \u00e0 Junas est une aventure artistique, culturelle et humaine forte. Un jazz [&#8230;]\n","protected":false},"author":229,"featured_media":5354,"template":"","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":""},"tags":[],"tribe_events_cat":[20],"class_list":["post-5352","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-presentiel-citoyennete","cat_presentiel-citoyennete"],"ticketed":false,"_links":{"self":[{"href":"https:\/\/15francoallemandeoccitanie.fr\/de\/wp-json\/wp\/v2\/tribe_events\/5352","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/15francoallemandeoccitanie.fr\/de\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/15francoallemandeoccitanie.fr\/de\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/15francoallemandeoccitanie.fr\/de\/wp-json\/wp\/v2\/users\/229"}],"version-history":[{"count":1,"href":"https:\/\/15francoallemandeoccitanie.fr\/de\/wp-json\/wp\/v2\/tribe_events\/5352\/revisions"}],"predecessor-version":[{"id":5400,"href":"https:\/\/15francoallemandeoccitanie.fr\/de\/wp-json\/wp\/v2\/tribe_events\/5352\/revisions\/5400"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/15francoallemandeoccitanie.fr\/de\/wp-json\/wp\/v2\/media\/5354"}],"wp:attachment":[{"href":"https:\/\/15francoallemandeoccitanie.fr\/de\/wp-json\/wp\/v2\/media?parent=5352"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/15francoallemandeoccitanie.fr\/de\/wp-json\/wp\/v2\/tags?post=5352"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/15francoallemandeoccitanie.fr\/de\/wp-json\/wp\/v2\/tribe_events_cat?post=5352"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}